{"id":998529,"date":"2024-12-10T11:33:41","date_gmt":"2024-12-10T10:33:41","guid":{"rendered":"https:\/\/www.aldivia.com\/2024\/12\/10\/viazest-calendula-os30f-conventional-organic\/"},"modified":"2026-04-16T12:21:09","modified_gmt":"2026-04-16T10:21:09","slug":"viazest-calendula-os30f-conventional-organic","status":"publish","type":"post","link":"https:\/\/www.aldivia.com\/en\/2024\/12\/10\/viazest-calendula-os30f-conventional-organic\/","title":{"rendered":"VIAZEST<sup>\u00ae<\/sup> Calendula OS30F <br>(Fat Soluble)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"998529\" class=\"elementor elementor-998529 elementor-992474\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3007c039 e-flex e-con-boxed e-con e-parent\" data-id=\"3007c039\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-6b25af44 elementor-widget elementor-widget-text-editor\" data-id=\"6b25af44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>L&#8217;extrait lipidique de calendula, VIAZEST<sup>\u00ae<\/sup> Calendula OS30F est utilis\u00e9 dans des onguents pour soulager les probl\u00e8mes de peaux (ecz\u00e9ma) et les blessures mineures (varices, h\u00e9morro\u00efdes).\nIl est \u00e9galement pr\u00e9conis\u00e9 dans les produits pour peaux sensibles, les soins du corps, le contour des yeux et dans les produits de massage pour les jambes. Il est recommand\u00e9 pour les peaux d\u00e9licates, s\u00e8ches et irrit\u00e9es. L&#8217;extrait lipidique de calendula entre dans la composition de cr\u00e8mes adoucissantes et calmantes, des produits solaires (contre les coups de soleil), des shampooings et apr\u00e8s shampooings.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>VIAZEST<sup>\u00ae<\/sup> Calendula OS30F Liposoluble. Concentrated macerate of calendula flowers in sunflower oil with, soothing, softening and antiseptic properties.<\/p>\n","protected":false},"author":1,"featured_media":998257,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[157],"tags":[],"class_list":["post-998529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viazest-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/posts\/998529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/comments?post=998529"}],"version-history":[{"count":1,"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/posts\/998529\/revisions"}],"predecessor-version":[{"id":1002174,"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/posts\/998529\/revisions\/1002174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/media\/998257"}],"wp:attachment":[{"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/media?parent=998529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/categories?post=998529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aldivia.com\/en\/wp-json\/wp\/v2\/tags?post=998529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}